

{"id":46,"date":"2021-05-18T21:35:15","date_gmt":"2021-05-18T21:35:15","guid":{"rendered":"http:\/\/alimentosyvinosdeespana.com\/?p=46"},"modified":"2021-05-19T02:18:00","modified_gmt":"2021-05-19T02:18:00","slug":"aceite-de-oliva-100-purosabor-intenso-2","status":"publish","type":"post","link":"https:\/\/alimentosyvinosdeespana.com\/index.php\/2021\/05\/18\/aceite-de-oliva-100-purosabor-intenso-2\/","title":{"rendered":"Aceite de Oliva 100% Puro (Sabor Intenso)"},"content":{"rendered":"\n<p><strong>Contenido neto 1000 ml<\/strong><\/p>\n\n\n\n<p>Es un <span style=\"color:#ad000a\" class=\"has-inline-color\">Aceite 100% Puro<\/span> obtenido s\u00f3lo de aceitunas y que resulta de la mezcla de aceites de oliva v\u00edrgenes y aceites refinados de oliva.<br><br>El <span style=\"color:#ad000a\" class=\"has-inline-color\">Aceite de Oliva 100% Puro<\/span> es el aceite ideal para elaborar todos aquellos platos en los que no se quiera ocultar los sabores propios de cada uno de los alimentos, ofreciendo adem\u00e1s, un gran aporte de Vitamina E.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contenido neto 1000 ml Es un Aceite 100% Puro obtenido s\u00f3lo de aceitunas y que resulta de la mezcla de aceites de oliva v\u00edrgenes y aceites refinados de oliva. El Aceite de Oliva 100% Puro es el aceite ideal para elaborar todos aquellos platos en los que no se quiera ocultar los sabores propios de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/posts\/46"}],"collection":[{"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":2,"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"predecessor-version":[{"id":82,"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/posts\/46\/revisions\/82"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/media\/25"}],"wp:attachment":[{"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alimentosyvinosdeespana.com\/index.php\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}